{"id":70373,"count":43,"description":"","link":"https:\/\/shuttershopegypt.com\/ar\/product-category\/audio\/headphones-earphones\/wired\/","name":"\u0633\u0644\u0643\u064a","slug":"wired","taxonomy":"product_cat","parent":70372,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wired - SHUTTER SHOP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shuttershopegypt.com\/ar\/product-category\/audio\/headphones-earphones\/wired\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wired\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shuttershopegypt.com\/ar\/product-category\/audio\/headphones-earphones\/wired\/\" \/>\n<meta property=\"og:site_name\" content=\"SHUTTER SHOP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/product-category\\\/audio\\\/headphones-earphones\\\/wired\\\/\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/product-category\\\/audio\\\/headphones-earphones\\\/wired\\\/\",\"name\":\"Wired - SHUTTER SHOP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/product-category\\\/audio\\\/headphones-earphones\\\/wired\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/product-category\\\/audio\\\/headphones-earphones\\\/wired\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Audio\",\"item\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/product-category\\\/audio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Headphones &amp; Earphones\",\"item\":\"https:\\\/\\\/shuttershopegypt.com\\\/ar\\\/product-category\\\/audio\\\/headphones-earphones\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Wired\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/\",\"name\":\"SHUTTER SHOP\",\"description\":\"Your go-to shop for everything production and more!\",\"publisher\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#organization\"},\"alternateName\":\"SHUTTER SHOP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#organization\",\"name\":\"SHUTTER SHOP\",\"alternateName\":\"SHUTTER SHOP\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/final-logo-1024.png\",\"contentUrl\":\"https:\\\/\\\/shuttershopegypt.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/final-logo-1024.png\",\"width\":1024,\"height\":1024,\"caption\":\"SHUTTER SHOP\"},\"image\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SHUTTERSCO\"],\"email\":\"info@shuttershopegypt.com\",\"telephone\":\"01222996858\",\"legalName\":\"Bridges Trading\",\"vatID\":\"552-310-018\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wired - SHUTTER SHOP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shuttershopegypt.com\/ar\/product-category\/audio\/headphones-earphones\/wired\/","og_locale":"ar_AR","og_type":"article","og_title":"Wired","og_url":"https:\/\/shuttershopegypt.com\/ar\/product-category\/audio\/headphones-earphones\/wired\/","og_site_name":"SHUTTER SHOP","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/shuttershopegypt.com\/en\/product-category\/audio\/headphones-earphones\/wired\/","url":"https:\/\/shuttershopegypt.com\/en\/product-category\/audio\/headphones-earphones\/wired\/","name":"Wired - SHUTTER SHOP","isPartOf":{"@id":"https:\/\/shuttershopegypt.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/shuttershopegypt.com\/en\/product-category\/audio\/headphones-earphones\/wired\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/shuttershopegypt.com\/en\/product-category\/audio\/headphones-earphones\/wired\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shuttershopegypt.com\/en\/"},{"@type":"ListItem","position":2,"name":"Audio","item":"https:\/\/shuttershopegypt.com\/en\/product-category\/audio\/"},{"@type":"ListItem","position":3,"name":"Headphones &amp; Earphones","item":"https:\/\/shuttershopegypt.com\/ar\/product-category\/audio\/headphones-earphones\/"},{"@type":"ListItem","position":4,"name":"Wired"}]},{"@type":"WebSite","@id":"https:\/\/shuttershopegypt.com\/en\/#website","url":"https:\/\/shuttershopegypt.com\/en\/","name":"SHUTTER SHOP","description":"\u0645\u062a\u062c\u0631\u0643 \u0627\u0644\u0645\u0641\u0636\u0644 \u0644\u0643\u0644 \u0634\u064a\u0621 \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0648\u0623\u0643\u062b\u0631!","publisher":{"@id":"https:\/\/shuttershopegypt.com\/en\/#organization"},"alternateName":"SHUTTER SHOP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shuttershopegypt.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/shuttershopegypt.com\/en\/#organization","name":"SHUTTER SHOP","alternateName":"SHUTTER SHOP","url":"https:\/\/shuttershopegypt.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/shuttershopegypt.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/06\/final-logo-1024.png","contentUrl":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/06\/final-logo-1024.png","width":1024,"height":1024,"caption":"SHUTTER SHOP"},"image":{"@id":"https:\/\/shuttershopegypt.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SHUTTERSCO"],"email":"info@shuttershopegypt.com","telephone":"01222996858","legalName":"Bridges Trading","vatID":"552-310-018","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/shuttershopegypt.com\/ar\/wp-json\/wp\/v2\/product_cat\/70373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shuttershopegypt.com\/ar\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/shuttershopegypt.com\/ar\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/shuttershopegypt.com\/ar\/wp-json\/wp\/v2\/product_cat\/70372"}],"wp:post_type":[{"href":"https:\/\/shuttershopegypt.com\/ar\/wp-json\/wp\/v2\/product?product_cat=70373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}