{"id":126608291,"date":"2024-08-14T02:38:42","date_gmt":"2024-08-13T23:38:42","guid":{"rendered":"https:\/\/shuttershopegypt.com\/?post_type=product&#038;p=126608291"},"modified":"2026-06-25T18:18:19","modified_gmt":"2026-06-25T15:18:19","slug":"anker-a2620l22-powerport-mini-12w-wall-charger-white","status":"publish","type":"product","link":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/","title":{"rendered":"Anker A2620L22 PowerPort Mini 12W Wall Charger &#8211; White"},"content":{"rendered":"<h2>Anker A2620L22 PowerPort Mini Overview:<\/h2>\n<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li>Description File:Anker logo.svg &#8211; Wikimedia Commons Anker PowerPort Mini 2-Port Wall Charger &#8211; [A2620L22] Power Port Mini Dual Port Wall Charger Super Compact USB Charger, 2.4A Output &amp; Foldable Plug for iPhone X \/ 8\/7 \/ Plus, iPad Pro\/Air 2 \/ Mini 4, Samsung, and More Itsy Bitsy, Teenie Weenie A super compact design saves space on the wall, or fits perfectly into palm, pack, or pocket. Just when you thought it couldn&#8217;t get any smaller, the plug folds away, to go absolutely everywhere you need to go. The Need for Speed Anker&#8217;s world-famous PowerIQ charging technology enables tailored charging of a multitude of devices, by intelligently determining which device is plugged in to charge, and adjusting output accordingly. One for Two Charge 2 USB devices at the same time. You&#8217;re about to discover just how convenient your mobile devices can be. Multi-Protect Overvoltage protection, temperature control, and more combine to create the ultimate safety system, letting you charge with total peace of mind. Note -Power Port mini provides fast charging up to 12W for one device, and delivers a total of 12W from both ports while charging 2 devices simultaneously. Features: \u2022 From Anker, America&#8217;s Leading USB Charging Brand \u2022 Faster and safer charging with our advanced technology \u2022 30 million+ happy users and counting<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Key Features:<\/strong><\/p>\n<ul>\n<li><span class=\"a-list-item\">High-Speed Charging<\/span><\/li>\n<li><span class=\"a-list-item\">Number of ports: 2<\/span><\/li>\n<li><span class=\"a-list-item\">Compatible with multi devices<\/span><\/li>\n<li><span class=\"a-list-item\">Packed with features<\/span><\/li>\n<\/ul>\n","protected":false},"featured_media":126608326,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[70253,70247],"product_tag":[52391,53046,54449,54874,60449,62843,62929],"class_list":["post-126608291","product","type-product","status-publish","has-post-thumbnail","product_cat-chargers-mobiles","product_cat-mobilesaccessories","product_tag-12w","product_tag-24delivery","product_tag-a2620l22-ar","product_tag-anker","product_tag-powerport-mini","product_tag-wall-charger","product_tag-white","pa_brands-anker","pa_delivery-2-4-days-delivery","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anker A2620L22 PowerPort Mini 12W Wall Charger - White - SHUTTER SHOP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anker A2620L22 PowerPort Mini 12W Wall Charger - White\" \/>\n<meta property=\"og:description\" content=\"Key Features:   High-Speed Charging  Number of ports: 2  Compatible with multi devices  Packed with features\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/\" \/>\n<meta property=\"og:site_name\" content=\"SHUTTER SHOP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SHUTTERSCO\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T15:18:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/08\/1-9-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"450&nbsp;EGP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/\",\"name\":\"Anker A2620L22 PowerPort Mini 12W Wall Charger - White - SHUTTER SHOP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shuttershopegypt.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/1-9-3.jpg\",\"datePublished\":\"2024-08-13T23:38:42+00:00\",\"dateModified\":\"2026-06-25T15:18:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/1-9-3.jpg\",\"contentUrl\":\"https:\\\/\\\/shuttershopegypt.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/1-9-3.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop-2\\\/anker-a2620l22-powerport-mini-12w-wall-charger-white\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anker A2620L22 PowerPort Mini 12W Wall Charger &#8211; White\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/\",\"name\":\"SHUTTER SHOP\",\"description\":\"Your go-to shop for everything production and more!\",\"publisher\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#organization\"},\"alternateName\":\"SHUTTER SHOP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#organization\",\"name\":\"SHUTTER SHOP\",\"alternateName\":\"SHUTTER SHOP\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shuttershopegypt.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/final-logo-1024.png\",\"contentUrl\":\"https:\\\/\\\/shuttershopegypt.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/final-logo-1024.png\",\"width\":1024,\"height\":1024,\"caption\":\"SHUTTER SHOP\"},\"image\":{\"@id\":\"https:\\\/\\\/shuttershopegypt.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SHUTTERSCO\"],\"email\":\"info@shuttershopegypt.com\",\"telephone\":\"01222996858\",\"legalName\":\"Bridges Trading\",\"vatID\":\"552-310-018\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Anker\" \/>\n<meta property=\"product:price:amount\" content=\"450\" \/>\n<meta property=\"product:price:currency\" content=\"EGP\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A2620L22\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anker A2620L22 PowerPort Mini 12W Wall Charger - White - SHUTTER SHOP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/","og_locale":"en_US","og_type":"article","og_title":"Anker A2620L22 PowerPort Mini 12W Wall Charger - White","og_description":"Key Features:   High-Speed Charging  Number of ports: 2  Compatible with multi devices  Packed with features","og_url":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/","og_site_name":"SHUTTER SHOP","article_publisher":"https:\/\/www.facebook.com\/SHUTTERSCO","article_modified_time":"2026-06-25T15:18:19+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/08\/1-9-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"450&nbsp;EGP","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/","url":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/","name":"Anker A2620L22 PowerPort Mini 12W Wall Charger - White - SHUTTER SHOP","isPartOf":{"@id":"https:\/\/shuttershopegypt.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/#primaryimage"},"image":{"@id":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/#primaryimage"},"thumbnailUrl":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/08\/1-9-3.jpg","datePublished":"2024-08-13T23:38:42+00:00","dateModified":"2026-06-25T15:18:19+00:00","breadcrumb":{"@id":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/#primaryimage","url":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/08\/1-9-3.jpg","contentUrl":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/08\/1-9-3.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/shuttershopegypt.com\/en\/shop-2\/anker-a2620l22-powerport-mini-12w-wall-charger-white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shuttershopegypt.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/shuttershopegypt.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Anker A2620L22 PowerPort Mini 12W Wall Charger &#8211; White"}]},{"@type":"WebSite","@id":"https:\/\/shuttershopegypt.com\/en\/#website","url":"https:\/\/shuttershopegypt.com\/en\/","name":"SHUTTER SHOP","description":"Your go-to shop for everything production and more!","publisher":{"@id":"https:\/\/shuttershopegypt.com\/en\/#organization"},"alternateName":"SHUTTER SHOP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shuttershopegypt.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shuttershopegypt.com\/en\/#organization","name":"SHUTTER SHOP","alternateName":"SHUTTER SHOP","url":"https:\/\/shuttershopegypt.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shuttershopegypt.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/06\/final-logo-1024.png","contentUrl":"https:\/\/shuttershopegypt.com\/wp-content\/uploads\/2024\/06\/final-logo-1024.png","width":1024,"height":1024,"caption":"SHUTTER SHOP"},"image":{"@id":"https:\/\/shuttershopegypt.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SHUTTERSCO"],"email":"info@shuttershopegypt.com","telephone":"01222996858","legalName":"Bridges Trading","vatID":"552-310-018","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]},"product_brand":"Anker","product_price_amount":"450","product_price_currency":"EGP","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A2620L22","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/product\/126608291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/comments?post=126608291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/media\/126608326"}],"wp:attachment":[{"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/media?parent=126608291"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/product_brand?post=126608291"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/product_cat?post=126608291"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shuttershopegypt.com\/en\/wp-json\/wp\/v2\/product_tag?post=126608291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}